{"id":21338,"date":"2023-11-20T10:54:18","date_gmt":"2023-11-20T09:54:18","guid":{"rendered":"https:\/\/en-desarrollo.eu\/casadelamemoria\/artista\/manuel-pajares\/"},"modified":"2023-11-22T18:57:06","modified_gmt":"2023-11-22T17:57:06","slug":"manuel-pajares","status":"publish","type":"artista","link":"https:\/\/casadelamemoria.es\/fr\/artiste\/manuel-pajares\/","title":{"rendered":"Manuel Pajares"},"content":{"rendered":"\n<p>Francisco Manuel Pajares Carmona est n\u00e9 \u00e0 Santa Amalia (Badajoz).<\/p>\n\n<p>Depuis qu&rsquo;il a commenc\u00e9 sa carri\u00e8re \u00e0 l&rsquo;\u00e2ge de 15 ans, il a remport\u00e9 de nombreux prix dans toute l&rsquo;Espagne et s&rsquo;est produit dans des festivals de musique tr\u00e8s prestigieux comme le \u00ab CICLO FLAMENCO EN LA PLAZA ALTA \u00bb ou le \u00ab WOMAD \u00bb \u00e0 C\u00e1ceres.<\/p>\n\n<p>Elle commence \u00e0 faire partie de la Maison de la M\u00e9moire fin 2022.<\/p>\n\n<p>Il est entre autres Premier Prix du Concours Jeunesse SUMA FLAMENCA \u00e0 Madrid, EL GALLO \u00e0 Mor\u00f3n, Prix Soleares et Prix Naranjito de Triana \u00e0 S\u00e9ville.<\/p>\n\n<p>Un chanteur capable de tous les registres, aussi bien des gradations douces que du quej\u00edo au bon moment, la ma\u00eetrise totale du compas, la d\u00e9licatesse et le bon go\u00fbt dans son chant, la clart\u00e9 expressive, l&rsquo;air frais de sa mani\u00e8re particuli\u00e8re est la base d&rsquo;un chanteur d\u00e9j\u00e0 form\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francisco Manuel Pajares Carmona est n\u00e9 \u00e0 Santa Amalia (Badajoz). Depuis qu&rsquo;il a commenc\u00e9 sa carri\u00e8re \u00e0 l&rsquo;\u00e2ge de 15 ans, il a remport\u00e9 de nombreux prix dans toute l&rsquo;Espagne et s&rsquo;est produit dans des festivals de musique tr\u00e8s prestigieux comme le \u00ab CICLO FLAMENCO EN LA PLAZA ALTA \u00bb ou le \u00ab WOMAD \u00bb &#8230; <a title=\"Manuel Pajares\" class=\"read-more\" href=\"https:\/\/casadelamemoria.es\/fr\/artiste\/manuel-pajares\/\" aria-label=\"En savoir plus sur Manuel Pajares\">Lire la suite<\/a><\/p>\n","protected":false},"featured_media":21356,"template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false},"categories":[230],"tags":[],"class_list":["post-21338","artista","type-artista","status-publish","has-post-thumbnail","hentry","category-al-cante"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/artista\/21338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/artista"}],"about":[{"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/types\/artista"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/media\/21356"}],"wp:attachment":[{"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/media?parent=21338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/categories?post=21338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadelamemoria.es\/fr\/wp-json\/wp\/v2\/tags?post=21338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}